{"id":9757,"date":"2023-07-25T15:17:54","date_gmt":"2023-07-25T13:17:54","guid":{"rendered":"https:\/\/bioma.com\/prodotti\/"},"modified":"2024-03-26T10:28:54","modified_gmt":"2024-03-26T09:28:54","slug":"prodotti","status":"publish","type":"page","link":"https:\/\/bioma.com\/it\/prodotti\/","title":{"rendered":"Prodotti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9757\" class=\"elementor elementor-9757 elementor-7940\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16bd1d07 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16bd1d07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23db1435\" data-id=\"23db1435\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-453e30ca elementor-widget elementor-widget-heading\" data-id=\"453e30ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Prodotti<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea5c41b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea5c41b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7125d1ad\" data-id=\"7125d1ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e56afe2 elementor-widget elementor-widget-image\" data-id=\"1e56afe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"408\" height=\"408\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png\" class=\"attachment-full size-full wp-image-8709\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png 408w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black-300x300.png 300w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black-100x100.png 100w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black-150x150.png 150w\" sizes=\"(max-width: 408px) 100vw, 408px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f3fe7ba elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f3fe7ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e9fd0ca\" data-id=\"6e9fd0ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14c1394c elementor-widget elementor-widget-heading\" data-id=\"14c1394c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zootecnia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3afa5ba6 elementor-widget elementor-widget-text-editor\" data-id=\"3afa5ba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nostra gamma di prodotti microbiologici e enzimatici si distingue per le sue certificazioni \u201cSenza prodotti chimici\u201d, \u201cSenza OGM\u201d e \u201cSenza rischi\u201d. Il nostro obiettivo principale \u00e8 ridurre notevolmente le emissioni di ammoniaca e altri gas dannosi, contribuendo cos\u00ec a migliorare il benessere del bestiame e aumentarne la produttivit\u00e0. Questo innovativo prodotto stabilisce un equilibrio all&#8217;interno delle biomasse prodotte dai vostri animali, favorendo un maggior sfruttamento di materiali organici come letame e liquami. Ci\u00f2 si traduce in un aumento della loro biodisponibilit\u00e0 nei vostri terreni, con un impatto significativo sulla loro qualit\u00e0 e fertilit\u00e0. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3a43ceff\" data-id=\"3a43ceff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e765c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c9e765c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kopros-b\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"711\" height=\"261\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-B.png\" class=\"attachment-full size-full wp-image-12626\" alt=\"Icon von Schaf und Kuh\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-B.png 711w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-B-300x110.png 300w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-B-600x220.png 600w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kopros-b\/\">Kopros\u00ae B<\/a><\/h3><p class=\"elementor-image-box-description\">Microrganismi accuratamente selezionati per ridurre la presenza di ammoniaca, accelerare il processo di decomposizione della materia organica bovina e ovina, trasformandola in un fertilizzante di alta qualit\u00e0.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19a00a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"19a00a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kopros-b\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kopros\u00ae B<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9fe2f8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a9fe2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kopros-c\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"738\" height=\"364\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-C.png\" class=\"attachment-full size-full wp-image-12630\" alt=\"Icon von Huhn und Hase\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-C.png 738w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-C-300x148.png 300w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-C-600x296.png 600w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kopros-c\/\">Kopros\u00ae C<\/a><\/h3><p class=\"elementor-image-box-description\">Microrganismi accuratamente selezionati per ridurre la presenza di ammoniaca e accelerare il processo di decomposizione della materia organica avicola e cunicola, trasformandola in un fertilizzante di alta qualit\u00e0.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c32f79b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1c32f79b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kopros-c\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kopros\u00ae C<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a7347 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"72a7347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kopros-h\/%20\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"330\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-H.png\" class=\"attachment-full size-full wp-image-12640\" alt=\"Icon eines Pferdes\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-H.png 386w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-H-300x256.png 300w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kopros-h\/%20\">Kopros\u00ae H<\/a><\/h3><p class=\"elementor-image-box-description\">Microrganismi accuratamente selezionati per ridurre la presenza di ammoniaca, accelerare il processo di decomposizione della materia organica equina, trasformandola in un fertilizzante di alta qualit\u00e0.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54668479 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"54668479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/kopros-h\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kopros\u00ae H<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5bd01f91\" data-id=\"5bd01f91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d9b25f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9d9b25f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kopros-p\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"239\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-P.png\" class=\"attachment-full size-full wp-image-12650\" alt=\"Icon eines Schweines\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-P.png 375w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-P-300x191.png 300w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kopros-p\/\">Kopros\u00ae P<\/a><\/h3><p class=\"elementor-image-box-description\">Microrganismi accuratamente selezionati per ridurre la presenza di ammoniaca, accelerare il processo di decomposizione della materia organica suina, trasformandola in un fertilizzante di alta qualit\u00e0.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e55b5f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"27e55b5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kopros-p\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kopros\u00ae P<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca0ed43 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ca0ed43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kopros-s\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"301\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-S.png\" class=\"attachment-full size-full wp-image-12654\" alt=\"Icon einer Ziege\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-S.png 333w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Kopros-S-300x271.png 300w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kopros-s\/\">Kopros\u00ae S<\/a><\/h3><p class=\"elementor-image-box-description\">Microrganismi accuratamente selezionati per ridurre la presenza di ammoniaca, accelerare il processo di decomposizione della materia organica caprina, trasformandola in un fertilizzante di alta qualit\u00e0.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5163bff8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5163bff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kopros-s\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kopros\u00ae S<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-332909ad elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"332909ad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10b34002\" data-id=\"10b34002\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c8628c1 elementor-widget elementor-widget-heading\" data-id=\"6c8628c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agricoltura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d49e28 elementor-widget elementor-widget-text-editor\" data-id=\"5d49e28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nostra gamma di prodotti microbiologici enzimatici si distingue per le sue certificazioni &#8220;Senza prodotti chimici&#8221;, &#8220;Senza OGM&#8221; e &#8220;Senza rischi&#8221;.<\/p>\n<p>Il loro obiettivo principale \u00e8 ottimizzare i processi di trasformazione dei composti organici e inorganici riducendo la dipendenza dai fertilizzanti chimici.<\/p>\n<p>Questi prodotti facilitano la disponibilit\u00e0 degli elementi nutritivi essenziali per le piante, contribuendo a migliorare sia la qualit\u00e0 che la quantit\u00e0 dei raccolti. Svolgono un ruolo cruciale nell&#8217;assicurare un adeguato apporto di nutrienti, promuovendo cos\u00ec una crescita sana e produttiva delle colture.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1d34200d\" data-id=\"1d34200d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6761af elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c6761af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"323\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1.png\" class=\"attachment-full size-full wp-image-11694\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1.png 180w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1-167x300.png 167w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\" class=\"elementor-inline-editing pen\" data-elementor-setting-key=\"title_text\" data-elementor-inline-editing-toolbar=\"none\" data-pen-placeholder=\"Eingabe hier...\" style=\"border-color: transparent;font-size: 20px\">Ampelos\u00ae<\/a><\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione del vigneto<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ace1b71 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6ace1b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/ampelos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Ampelos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de2d36 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6de2d36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/carpos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"307\" height=\"348\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos.webp\" class=\"attachment-full size-full wp-image-14683\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos.webp 307w, https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos-265x300.webp 265w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/carpos\/\">Carpos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma per la biofertilizzazione delle colture arboree ed arbustive<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ff96f3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9ff96f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/carpos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Carpos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e70a8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"00e70a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/empsico\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"308\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico.png\" class=\"attachment-full size-full wp-image-11676\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico.png 336w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico-300x275.png 300w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/empsico\/\">Empsico\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programme di bioattivazione per terreni da pascolo o coltivati a foraggio<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4501cbc0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4501cbc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/empsico\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Empsico\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7fc91925\" data-id=\"7fc91925\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2433c49 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2433c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/fylo\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"275\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo.png\" class=\"attachment-full size-full wp-image-11684\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo.png 312w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo-300x264.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/fylo\/\">Fylo\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Trattamento fogliare per tutte le colture<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78b617d9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"78b617d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/fylo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Fylo\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e2374 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d2e2374\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/kipos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"306\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos.png\" class=\"attachment-full size-full wp-image-11672\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos.png 352w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos-300x261.png 300w\" sizes=\"(max-width: 352px) 100vw, 352px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/kipos\/\">Kipos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione per le colture di campo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f644e34 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1f644e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kipos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kipos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d1bbac elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6d1bbac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/sporos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"306\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos.png\" class=\"attachment-full size-full wp-image-11680\" alt=\"Icon von Sporos\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos.png 311w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos-300x295.png 300w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/sporos\/\">Sporos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione per le colture di campo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93eecf7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"93eecf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/sporos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Sporos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23ea0b72 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23ea0b72\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-796c4204\" data-id=\"796c4204\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2bc63d elementor-widget elementor-widget-heading\" data-id=\"e2bc63d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agroalimentare<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75184947 elementor-widget elementor-widget-text-editor\" data-id=\"75184947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n\nBioma ha sviluppato una gamma di prodotti completamente privi di prodotti chimici per ottimizzare le fasi cruciali della fermentazione, garantendo cos\u00ec la stabilit\u00e0 delle birre artigianali.\n\nIntegrando Empyra\u00ae, un ausiliario naturale, riusciamo non solo a ottimizzare i processi di fermentazione, ma anche a esercitare un controllo microbiologico e garantire una stabilit\u00e0 fisica duratura.\n\nQuesto approccio consente alle birre artigianali di esprimere appieno le caratteristiche delle materie prime utilizzate, migliorandone la qualit\u00e0 preservandole dagli effetti negativi legati alle fasi di conservazione e trasporto.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22167c28\" data-id=\"22167c28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7a529c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a7a529c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/empyra\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"315\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empyra-2.png\" class=\"attachment-full size-full wp-image-11854\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empyra-2.png 275w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empyra-2-262x300.png 262w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/empyra\/\">Empyra\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma senza sostanze chimiche per birre artigianali<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1012c786 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1012c786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/empyra\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Empyra\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3eac420a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3eac420a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6150779a\" data-id=\"6150779a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ba942c6 elementor-widget elementor-widget-heading\" data-id=\"5ba942c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ambiente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad966d8 elementor-widget elementor-widget-text-editor\" data-id=\"6ad966d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bioma ha sviluppato una serie di prodotti completamente privi di prodotti chimici. Questa gamma mira a raggiungere obiettivi importanti, come la bonifica naturale dei suoli contaminati da idrocarburi, l&#8217;ottimizzazione dei processi di trattamento delle acque reflue nelle stazioni di depurazione e l&#8217;eliminazione degli odori nelle discariche. Questi prodotti sono appositamente progettati per intervenire in modo efficace nei complessi settori della decontaminazione ambientale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f8e1fc0\" data-id=\"6f8e1fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26218a3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"26218a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/idor\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"329\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Idor-1.png\" class=\"attachment-full size-full wp-image-11799\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Idor-1.png 236w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Idor-1-215x300.png 215w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/idor\/\">Idor\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Prodotto naturale per il trattamento delle acque reflue<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30c2a76d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"30c2a76d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/idor\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Idor\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7058a09 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7058a09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/synthetos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"329\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Synthetos-1.png\" class=\"attachment-full size-full wp-image-11940\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Synthetos-1.png 242w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Synthetos-1-221x300.png 221w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/synthetos\/\">Synthetos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma di compostaggio degli scarti vegetali<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20c6922c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"20c6922c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/synthetos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Synthetos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Prodotti Zootecnia La nostra gamma di prodotti microbiologici e enzimatici si distingue per le sue certificazioni \u201cSenza prodotti chimici\u201d, \u201cSenza OGM\u201d e \u201cSenza rischi\u201d. Il nostro obiettivo principale \u00e8 ridurre notevolmente le emissioni di ammoniaca e altri gas dannosi, contribuendo cos\u00ec a migliorare il benessere del bestiame e aumentarne la produttivit\u00e0. Questo innovativo prodotto stabilisce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9757","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prodotti - Bioma SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bioma.com\/it\/prodotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prodotti - Bioma SA\" \/>\n<meta property=\"og:description\" content=\"Prodotti Zootecnia La nostra gamma di prodotti microbiologici e enzimatici si distingue per le sue certificazioni \u201cSenza prodotti chimici\u201d, \u201cSenza OGM\u201d e \u201cSenza rischi\u201d. Il nostro obiettivo principale \u00e8 ridurre notevolmente le emissioni di ammoniaca e altri gas dannosi, contribuendo cos\u00ec a migliorare il benessere del bestiame e aumentarne la produttivit\u00e0. Questo innovativo prodotto stabilisce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bioma.com\/it\/prodotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioma SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089638826673\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T09:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/\",\"name\":\"Prodotti - Bioma SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Bioma_O_black.png\",\"datePublished\":\"2023-07-25T13:17:54+00:00\",\"dateModified\":\"2024-03-26T09:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Bioma_O_black.png\",\"contentUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Bioma_O_black.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/prodotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bioma.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/\",\"name\":\"Bioma SA\",\"description\":\"Geolife Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#organization\"},\"alternateName\":\"Bioma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bioma.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#organization\",\"name\":\"Bioma SA\",\"alternateName\":\"Bioma\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_Bioma_black.png\",\"contentUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_Bioma_black.png\",\"width\":1383,\"height\":408,\"caption\":\"Bioma SA\"},\"image\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089638826673\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/69675437\",\"https:\\\/\\\/www.instagram.com\\\/bioma.sa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIZGmdEZWEC0Xc7w8oSKUkA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prodotti - Bioma SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bioma.com\/it\/prodotti\/","og_locale":"it_IT","og_type":"article","og_title":"Prodotti - Bioma SA","og_description":"Prodotti Zootecnia La nostra gamma di prodotti microbiologici e enzimatici si distingue per le sue certificazioni \u201cSenza prodotti chimici\u201d, \u201cSenza OGM\u201d e \u201cSenza rischi\u201d. Il nostro obiettivo principale \u00e8 ridurre notevolmente le emissioni di ammoniaca e altri gas dannosi, contribuendo cos\u00ec a migliorare il benessere del bestiame e aumentarne la produttivit\u00e0. Questo innovativo prodotto stabilisce [&hellip;]","og_url":"https:\/\/bioma.com\/it\/prodotti\/","og_site_name":"Bioma SA","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089638826673","article_modified_time":"2024-03-26T09:28:54+00:00","og_image":[{"url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bioma.com\/it\/prodotti\/","url":"https:\/\/bioma.com\/it\/prodotti\/","name":"Prodotti - Bioma SA","isPartOf":{"@id":"https:\/\/bioma.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bioma.com\/it\/prodotti\/#primaryimage"},"image":{"@id":"https:\/\/bioma.com\/it\/prodotti\/#primaryimage"},"thumbnailUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png","datePublished":"2023-07-25T13:17:54+00:00","dateModified":"2024-03-26T09:28:54+00:00","breadcrumb":{"@id":"https:\/\/bioma.com\/it\/prodotti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bioma.com\/it\/prodotti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bioma.com\/it\/prodotti\/#primaryimage","url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png","contentUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/Bioma_O_black.png"},{"@type":"BreadcrumbList","@id":"https:\/\/bioma.com\/it\/prodotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bioma.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Prodotti"}]},{"@type":"WebSite","@id":"https:\/\/bioma.com\/it\/#website","url":"https:\/\/bioma.com\/it\/","name":"Bioma SA","description":"Geolife Technology","publisher":{"@id":"https:\/\/bioma.com\/it\/#organization"},"alternateName":"Bioma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bioma.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/bioma.com\/it\/#organization","name":"Bioma SA","alternateName":"Bioma","url":"https:\/\/bioma.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bioma.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/logo_Bioma_black.png","contentUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/logo_Bioma_black.png","width":1383,"height":408,"caption":"Bioma SA"},"image":{"@id":"https:\/\/bioma.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089638826673","https:\/\/www.linkedin.com\/company\/69675437","https:\/\/www.instagram.com\/bioma.sa\/","https:\/\/www.youtube.com\/channel\/UCIZGmdEZWEC0Xc7w8oSKUkA"]}]}},"_links":{"self":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/comments?post=9757"}],"version-history":[{"count":5,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9757\/revisions"}],"predecessor-version":[{"id":14813,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9757\/revisions\/14813"}],"wp:attachment":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/media?parent=9757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}