{"id":9690,"date":"2023-07-03T15:35:46","date_gmt":"2023-07-03T13:35:46","guid":{"rendered":"https:\/\/bioma.com\/agricoltura\/"},"modified":"2024-03-26T10:45:56","modified_gmt":"2024-03-26T09:45:56","slug":"agricoltura","status":"publish","type":"page","link":"https:\/\/bioma.com\/it\/agricoltura\/","title":{"rendered":"Agricoltura"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9690\" class=\"elementor elementor-9690 elementor-6716\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33afd7c1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33afd7c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b98f55d\" data-id=\"3b98f55d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ed6fe40 elementor-widget elementor-widget-heading\" data-id=\"2ed6fe40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Agricoltura<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4263ce0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4263ce0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f16f4bc\" data-id=\"5f16f4bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c592ee3 elementor-widget elementor-widget-image\" data-id=\"c592ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"281\" height=\"320\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png\" class=\"attachment-full size-full wp-image-12891\" alt=\"Icon einer Windm\u00fchle\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png 281w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft-263x300.png 263w\" sizes=\"(max-width: 281px) 100vw, 281px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6lwzn3i elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6lwzn3i\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb31710\" data-id=\"bb31710\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01bf1c3 elementor-widget elementor-widget-heading\" data-id=\"01bf1c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agricoltura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65248c4 elementor-widget elementor-widget-text-editor\" data-id=\"65248c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La nostra gamma di prodotti microbiologici enzimatici si distingue per le sue certificazioni &#8220;Senza prodotti chimici&#8221;, &#8220;Senza OGM&#8221; e &#8220;Senza rischi&#8221;.<\/p>\n<p>Il loro obiettivo principale \u00e8 ottimizzare i processi di trasformazione dei composti organici e inorganici riducendo la dipendenza dai fertilizzanti chimici.<\/p>\n<p>Questi prodotti facilitano la disponibilit\u00e0 degli elementi nutritivi essenziali per le piante, contribuendo a migliorare sia la qualit\u00e0 che la quantit\u00e0 dei raccolti. Svolgono un ruolo cruciale nell&#8217;assicurare un adeguato apporto di nutrienti, promuovendo cos\u00ec una crescita sana e produttiva delle colture.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b8980b3\" data-id=\"b8980b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6a3c6d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d6a3c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"180\" height=\"323\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1.png\" class=\"attachment-full size-full wp-image-11694\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1.png 180w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Ampelos-1-167x300.png 167w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\" class=\"elementor-inline-editing pen\" data-elementor-setting-key=\"title_text\" data-elementor-inline-editing-toolbar=\"none\" data-pen-placeholder=\"Eingabe hier...\" style=\"border-color: transparent;font-size: 20px\">Ampelos\u00ae<\/a><\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione del vigneto<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0045ba8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0045ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/ampelos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Ampelos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b585948 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b585948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/carpos\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"307\" height=\"348\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos.webp\" class=\"attachment-full size-full wp-image-14683\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos.webp 307w, https:\/\/bioma.com\/wp-content\/uploads\/2024\/03\/Carpos-265x300.webp 265w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/carpos\/\">Carpos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma per la biofertilizzazione delle colture arboree ed arbustive<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359fe7d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"359fe7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/carpos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Carpos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-579b82e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"579b82e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/empsico\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"308\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico.png\" class=\"attachment-full size-full wp-image-11676\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico.png 336w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Empsico-300x275.png 300w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/empsico\/\">Empsico\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programme di bioattivazione per terreni da pascolo o coltivati a foraggio<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-745d386 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"745d386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/empsico\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai ad Empsico\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3a160ca\" data-id=\"3a160ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30475da elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"30475da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/fylo\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"275\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo.png\" class=\"attachment-full size-full wp-image-11684\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo.png 312w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Fylo-300x264.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/fylo\/\">Fylo\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Trattamento fogliare per tutte le colture<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12efcb6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"12efcb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/fylo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Fylo\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81996ea elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"81996ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"306\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos.png\" class=\"attachment-full size-full wp-image-11672\" alt=\"\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos.png 352w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Kipos-300x261.png 300w\" sizes=\"(max-width: 352px) 100vw, 352px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/ampelos\/\">Kipos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione per le colture di campo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-973936c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"973936c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/kipos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Kipos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d24593 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1d24593\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/bioma.com\/it\/sporos\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"306\" src=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos.png\" class=\"attachment-full size-full wp-image-11680\" alt=\"Icon von Sporos\" srcset=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos.png 311w, https:\/\/bioma.com\/wp-content\/uploads\/2023\/10\/Sporos-300x295.png 300w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/bioma.com\/it\/sporos\/\">Sporos\u00ae<\/a><\/h3><p class=\"elementor-image-box-description\">Programma di bioattivazione per le colture di campo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3182c6b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3182c6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/bioma.com\/it\/sporos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vai a Sporos\u00ae<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Agricoltura Agricoltura La nostra gamma di prodotti microbiologici enzimatici si distingue per le sue certificazioni &#8220;Senza prodotti chimici&#8221;, &#8220;Senza OGM&#8221; e &#8220;Senza rischi&#8221;. Il loro obiettivo principale \u00e8 ottimizzare i processi di trasformazione dei composti organici e inorganici riducendo la dipendenza dai fertilizzanti chimici. Questi prodotti facilitano la disponibilit\u00e0 degli elementi nutritivi essenziali per le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9690","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agricoltura - Bioma SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bioma.com\/it\/agricoltura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agricoltura - Bioma SA\" \/>\n<meta property=\"og:description\" content=\"Agricoltura Agricoltura La nostra gamma di prodotti microbiologici enzimatici si distingue per le sue certificazioni &#8220;Senza prodotti chimici&#8221;, &#8220;Senza OGM&#8221; e &#8220;Senza rischi&#8221;. Il loro obiettivo principale \u00e8 ottimizzare i processi di trasformazione dei composti organici e inorganici riducendo la dipendenza dai fertilizzanti chimici. Questi prodotti facilitano la disponibilit\u00e0 degli elementi nutritivi essenziali per le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bioma.com\/it\/agricoltura\/\" \/>\n<meta property=\"og:site_name\" content=\"Bioma SA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089638826673\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T09:45:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/\",\"name\":\"Agricoltura - Bioma SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Landwirtschaft.png\",\"datePublished\":\"2023-07-03T13:35:46+00:00\",\"dateModified\":\"2024-03-26T09:45:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Landwirtschaft.png\",\"contentUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Landwirtschaft.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/agricoltura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bioma.com\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agricoltura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/\",\"name\":\"Bioma SA\",\"description\":\"Geolife Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#organization\"},\"alternateName\":\"Bioma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bioma.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#organization\",\"name\":\"Bioma SA\",\"alternateName\":\"Bioma\",\"url\":\"https:\\\/\\\/bioma.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_Bioma_black.png\",\"contentUrl\":\"https:\\\/\\\/bioma.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_Bioma_black.png\",\"width\":1383,\"height\":408,\"caption\":\"Bioma SA\"},\"image\":{\"@id\":\"https:\\\/\\\/bioma.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089638826673\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/69675437\",\"https:\\\/\\\/www.instagram.com\\\/bioma.sa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIZGmdEZWEC0Xc7w8oSKUkA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agricoltura - Bioma SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bioma.com\/it\/agricoltura\/","og_locale":"it_IT","og_type":"article","og_title":"Agricoltura - Bioma SA","og_description":"Agricoltura Agricoltura La nostra gamma di prodotti microbiologici enzimatici si distingue per le sue certificazioni &#8220;Senza prodotti chimici&#8221;, &#8220;Senza OGM&#8221; e &#8220;Senza rischi&#8221;. Il loro obiettivo principale \u00e8 ottimizzare i processi di trasformazione dei composti organici e inorganici riducendo la dipendenza dai fertilizzanti chimici. Questi prodotti facilitano la disponibilit\u00e0 degli elementi nutritivi essenziali per le [&hellip;]","og_url":"https:\/\/bioma.com\/it\/agricoltura\/","og_site_name":"Bioma SA","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089638826673","article_modified_time":"2024-03-26T09:45:56+00:00","og_image":[{"url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bioma.com\/it\/agricoltura\/","url":"https:\/\/bioma.com\/it\/agricoltura\/","name":"Agricoltura - Bioma SA","isPartOf":{"@id":"https:\/\/bioma.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bioma.com\/it\/agricoltura\/#primaryimage"},"image":{"@id":"https:\/\/bioma.com\/it\/agricoltura\/#primaryimage"},"thumbnailUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png","datePublished":"2023-07-03T13:35:46+00:00","dateModified":"2024-03-26T09:45:56+00:00","breadcrumb":{"@id":"https:\/\/bioma.com\/it\/agricoltura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bioma.com\/it\/agricoltura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bioma.com\/it\/agricoltura\/#primaryimage","url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png","contentUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/11\/Landwirtschaft.png"},{"@type":"BreadcrumbList","@id":"https:\/\/bioma.com\/it\/agricoltura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bioma.com\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Agricoltura"}]},{"@type":"WebSite","@id":"https:\/\/bioma.com\/it\/#website","url":"https:\/\/bioma.com\/it\/","name":"Bioma SA","description":"Geolife Technology","publisher":{"@id":"https:\/\/bioma.com\/it\/#organization"},"alternateName":"Bioma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bioma.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/bioma.com\/it\/#organization","name":"Bioma SA","alternateName":"Bioma","url":"https:\/\/bioma.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bioma.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/logo_Bioma_black.png","contentUrl":"https:\/\/bioma.com\/wp-content\/uploads\/2023\/05\/logo_Bioma_black.png","width":1383,"height":408,"caption":"Bioma SA"},"image":{"@id":"https:\/\/bioma.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089638826673","https:\/\/www.linkedin.com\/company\/69675437","https:\/\/www.instagram.com\/bioma.sa\/","https:\/\/www.youtube.com\/channel\/UCIZGmdEZWEC0Xc7w8oSKUkA"]}]}},"_links":{"self":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/comments?post=9690"}],"version-history":[{"count":5,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9690\/revisions"}],"predecessor-version":[{"id":14822,"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/pages\/9690\/revisions\/14822"}],"wp:attachment":[{"href":"https:\/\/bioma.com\/it\/wp-json\/wp\/v2\/media?parent=9690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}